{"id":121,"date":"2025-05-17T08:18:50","date_gmt":"2025-05-17T07:18:50","guid":{"rendered":"https:\/\/www.gpsjammers.net\/?post_type=product&#038;p=121"},"modified":"2026-06-27T00:54:46","modified_gmt":"2026-06-26T23:54:46","slug":"315mhz-433mhz-868mhz-bloqueador-de-control-remoto-jammer-para-coche-y-garaje","status":"publish","type":"product","link":"https:\/\/www.gpsjammers.net\/es\/product\/315mhz-433mhz-868mhz-remote-control-jammer-blocker-car-garage-jammer\/","title":{"rendered":"Bloqueador de control remoto 315mhz, 433mhz, 868mhz, bloqueador de garaje para coches"},"content":{"rendered":"<p><strong>Caracter\u00edsticas de los inhibidores de control remoto:<\/strong><br \/>\nCada dispositivo bloquea solo un punto de frecuencia<br \/>\nAplicable para desactivar controles remotos de coches autom\u00e1ticos<br \/>\nCapaz de detener el control remoto de la puerta del garaje<br \/>\nPotencia de salida m\u00e1xima<br \/>\nRango de bloqueo flota dentro de 4MHz<br \/>\nPodr\u00eda hacer un punto de frecuencia similar designado<br \/>\nInofensivo para los humanos<br \/>\nViene con una garant\u00eda de un a\u00f1o<\/p>\n<p>Precauci\u00f3n:<br \/>\nEl inhibidor de control remoto debe usarse legalmente. El usuario ser\u00e1 completamente responsable de cualquier uso ilegal o cualquier infracci\u00f3n de derechos.<\/p>","protected":false},"excerpt":{"rendered":"<p>El inhibidor de control remoto port\u00e1til funciona en 315MHz, 433MHz o 868MHz. Est\u00e1 dise\u00f1ado para bloquear controles remotos inal\u00e1mbricos de mano, incluyendo control remoto de coche, control remoto de garaje, etc. El \u00e1rea de trabajo definida es de 5 a 20 metros de radio. Aplicable para desactivar y detener controles remotos de coches autom\u00e1ticos, etc.<\/p>\n<p>Frecuencia: 315\/433\/868MHz +\/- 2MHz<br \/>\nPotencia de salida: 1 \u2013 3Watt<br \/>\nCobertura: de 5 a 10 metros<br \/>\nFuente de alimentaci\u00f3n: bater\u00eda de 9V \u2013 12V<br \/>\nInterfaz: antena extensible<br \/>\nTemperatura: -30 a 60 grados<br \/>\nMaterial: caja de ABC<br \/>\nGarant\u00eda: 1 a\u00f1o<\/p>","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[21],"product_tag":[],"class_list":["post-121","product","type-product","status-publish","product_cat-remote-control-jammer","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.gpsjammers.net\/es\/wp-json\/wp\/v2\/product\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gpsjammers.net\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.gpsjammers.net\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gpsjammers.net\/es\/wp-json\/wp\/v2\/comments?post=121"}],"wp:attachment":[{"href":"https:\/\/www.gpsjammers.net\/es\/wp-json\/wp\/v2\/media?parent=121"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.gpsjammers.net\/es\/wp-json\/wp\/v2\/product_brand?post=121"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.gpsjammers.net\/es\/wp-json\/wp\/v2\/product_cat?post=121"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.gpsjammers.net\/es\/wp-json\/wp\/v2\/product_tag?post=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}